{"id":13559,"date":"2023-01-13T14:02:00","date_gmt":"2023-01-13T14:02:00","guid":{"rendered":"https:\/\/now-fertility.com\/services\/tests-genetiques-preimplantatoires-tcp\/"},"modified":"2026-04-01T17:23:35","modified_gmt":"2026-04-01T16:23:35","slug":"tests-genetiques-preimplantatoires-tcp","status":"publish","type":"page","link":"https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/","title":{"rendered":"FIV pour PGT"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13559\" class=\"elementor elementor-13559 elementor-13423\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6290ab1 e-flex e-con-boxed e-con e-parent\" data-id=\"6290ab1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;curve-asymmetrical&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M615.2,96.7C240.2,97.8,0,18.9,0,0v100h1000V0C1000,19.2,989.8,96,615.2,96.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f31f7d e-con-full e-flex e-con e-child\" data-id=\"4f31f7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c26d8b8 elementor-widget elementor-widget-heading\" data-id=\"c26d8b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xl\"><b>FIV pour PGT <\/b><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a9a8b9 elementor-widget elementor-widget-heading\" data-id=\"1a9a8b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S\u00e9lectionner des embryons sains pour une grossesse r\u00e9ussie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-024bf8f e-con-full e-flex e-con e-child\" data-id=\"024bf8f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c946fd1 elementor-align-left elementor-mobile-align-left elementor-widget elementor-widget-breadcrumbs\" data-id=\"c946fd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/now-fertility.com\/fr\/domicile\/\">Accueil<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e929a9 e-flex e-con-boxed e-con e-parent\" data-id=\"7e929a9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bebe31c e-con-full e-flex e-con e-child\" data-id=\"bebe31c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33e1da1 elementor-widget elementor-widget-heading\" data-id=\"33e1da1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PGT avec NOW-fertility<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24b867e elementor-widget elementor-widget-text-editor\" data-id=\"24b867e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019objectif des soins de fertilit\u00e9 est de vous aider \u00e0 avoir une grossesse et un b\u00e9b\u00e9 en bonne sant\u00e9. Le test g\u00e9n\u00e9tique pr\u00e9implantatoire (PGT) est une proc\u00e9dure de d\u00e9pistage effectu\u00e9e sur des embryons cr\u00e9\u00e9s par FIV pour v\u00e9rifier leur sant\u00e9 g\u00e9n\u00e9tique avant le transfert, augmentant ainsi les chances d\u2019une grossesse r\u00e9ussie et d\u2019un b\u00e9b\u00e9 en bonne sant\u00e9. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0ab53cc e-flex e-con-boxed e-con e-parent\" data-id=\"0ab53cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-065f750 e-con-full e-flex e-con e-child\" data-id=\"065f750\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3c56358 e-con-full e-flex e-con e-child\" data-id=\"3c56358\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3e138c0 e-con-full e-flex e-con e-child\" data-id=\"3e138c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3d8fec elementor-widget elementor-widget-heading\" data-id=\"a3d8fec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Une prise en charge personnalis\u00e9e pour maximiser vos chances de r\u00e9ussite<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cec114 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8cec114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Choix de cliniques de FIV avec des programmes de tests g\u00e9n\u00e9tiques avanc\u00e9s \u00e9tablis<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Expertise de laboratoire de pointe en culture d\u2019embryons jusqu\u2019au stade blastocyste et cong\u00e9lation<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tous les types de PGT (-A, -M et -SR) disponibles <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Interpr\u00e9tation experte des r\u00e9sultats des tests<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Soutien en conseil g\u00e9n\u00e9tique<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fe8216 e-con-full e-flex e-con e-child\" data-id=\"1fe8216\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e5bfb4 elementor-widget elementor-widget-spacer\" data-id=\"2e5bfb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a27eb51 e-con-full e-flex e-con e-child\" data-id=\"a27eb51\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-426ff1d elementor-widget elementor-widget-n-accordion\" data-id=\"426ff1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6960\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6960\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Types de PGT <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6960\" class=\"elementor-element elementor-element-2e984ed e-con-full e-flex e-con e-child\" data-id=\"2e984ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fceaae1 elementor-widget elementor-widget-text-editor\" data-id=\"fceaae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il existe diff\u00e9rents types de services de tests g\u00e9n\u00e9tiques utilis\u00e9s dans divers sc\u00e9narios. Lorsque vous d\u00e9cidez de subir ou non un PGT dans le cadre de votre cycle de FIV, votre sp\u00e9cialiste de la fertilit\u00e9, parfois en collaboration avec un conseiller g\u00e9n\u00e9tique, travaillera avec vous pour s\u00e9lectionner le meilleur test adapt\u00e9 \u00e0 vos ant\u00e9c\u00e9dents, votre cas clinique et vos pr\u00e9f\u00e9rences. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1ad3fb elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"f1ad3fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-f1ad3fb\" data-scroll-on-click=\"no\" data-scroll-speed=\"300\" data-accordion-id=\"f1ad3fb\" data-accordion-type=\"accordion\" data-toogle-speed=\"300\">\n            <div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"test-gntique-primplantatoire-pour-laneuplodie-pgt-a\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"1\" aria-controls=\"elementor-tab-content-2531\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">Test g\u00e9n\u00e9tique pr\u00e9implantatoire pour l\u2019aneuplo\u00efdie (PGT-A)<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-2531\" class=\"eael-accordion-content clearfix\" data-tab=\"1\" aria-labelledby=\"test-gntique-primplantatoire-pour-laneuplodie-pgt-a\"><p>Le PGT-A est la forme la plus courante de test d\u2019embryons. Il v\u00e9rifie si un embryon poss\u00e8de le bon nombre de chromosomes. Le nombre correct de chromosomes (46), \u00e9galement appel\u00e9 euplo\u00efde, est n\u00e9cessaire pour que l\u2019embryon devienne un enfant normal. Lorsque les cellules d\u2019un embryon ont un nombre incorrect de chromosomes, soit trop peu, soit trop, on parle alors d\u2019aneuplo\u00efdie. Il peut \u00e9galement vous indiquer si un embryon est masculin ou f\u00e9minin (XY ou XX).    <\/p>\n<p>La pr\u00e9valence des embryons aneuplo\u00efdes augmente avec l\u2019\u00e2ge des femmes. Les embryons pr\u00e9sentant une aneuplo\u00efdie sont plus susceptibles d\u2019entra\u00eener une fausse couche pr\u00e9coce ou un \u00e9chec de cycle de FIV, quelle que soit leur apparence morphologique. Moins fr\u00e9quemment, les embryons aneuplo\u00efdes peuvent entra\u00eener la naissance d\u2019un enfant atteint d\u2019une anomalie chromosomique, comme le syndrome de Down (trisomie 21).  <\/p>\n<p>En plus du syndrome de Down, le PGT-A peut d\u00e9tecter d\u2019autres anomalies g\u00e9n\u00e9tiques chromosomiques compl\u00e8tes telles que le syndrome de Turner (XO) et le syndrome de Klinefelter (XXY). Le PGT-A aurait un taux de pr\u00e9cision \u00e9lev\u00e9 d\u2019environ 98 %. <\/p>\n<p>Un embryon normal PGT-A a une chance estim\u00e9e de 60 % de donner lieu \u00e0 une naissance vivante apr\u00e8s un cycle de transfert. <\/p>\n<\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"test-gntique-primplantatoire-pour-les-maladies-monogniques-pgt-m\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"2\" aria-controls=\"elementor-tab-content-2532\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">Test g\u00e9n\u00e9tique pr\u00e9implantatoire pour les maladies monog\u00e9niques (PGT-M)<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-2532\" class=\"eael-accordion-content clearfix\" data-tab=\"2\" aria-labelledby=\"test-gntique-primplantatoire-pour-les-maladies-monogniques-pgt-m\"><p>Le PGT-M est utilis\u00e9 pour confirmer si une condition h\u00e9r\u00e9ditaire sp\u00e9cifique est pr\u00e9sente dans les embryons d\u2019une patiente. Il permet aux couples ayant une condition g\u00e9n\u00e9tique h\u00e9r\u00e9ditaire dans leur famille d\u2019\u00e9viter de la transmettre \u00e0 leurs enfants. Le PGT-M est g\u00e9n\u00e9ralement recommand\u00e9 dans les cas o\u00f9 l\u2019un des partenaires ou les deux ont des ant\u00e9c\u00e9dents connus de conditions g\u00e9n\u00e9tiques dans leur famille. Voici quelques exemples de maladies monog\u00e9niques courantes pouvant \u00eatre diagnostiqu\u00e9es avec le PGT-M : la thalass\u00e9mie, l\u2019h\u00e9mophilie A et B, le syndrome de l\u2019X fragile, la dr\u00e9panocytose, la mucoviscidose, la dystrophie musculaire de Duchenne, la maladie de Huntington et le syndrome de Marfan.    <\/p>\n<\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"test-gntique-primplantatoire-pour-les-rarrangements-chromosomiques-structurels-pgt-sr\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"3\" aria-controls=\"elementor-tab-content-2533\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">Test g\u00e9n\u00e9tique pr\u00e9implantatoire pour les r\u00e9arrangements chromosomiques structurels (PGT-SR)<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-2533\" class=\"eael-accordion-content clearfix\" data-tab=\"3\" aria-labelledby=\"test-gntique-primplantatoire-pour-les-rarrangements-chromosomiques-structurels-pgt-sr\"><p>Le PGT-SR identifie les embryons avec la bonne quantit\u00e9 de mat\u00e9riel g\u00e9n\u00e9tique (\u00e9quilibr\u00e9s\/normaux) et les embryons qui ont du mat\u00e9riel g\u00e9n\u00e9tique suppl\u00e9mentaire ou manquant \u00e0 la suite d\u2019une translocation ou d\u2019un r\u00e9arrangement (d\u00e9s\u00e9quilibr\u00e9s).<\/p>\n<p>Ce test est le moins courant et la plupart des patients n\u2019auront pas besoin de ce type de test. <\/p>\n<\/div>\n\t\t\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2767874 elementor-widget elementor-widget-button\" data-id=\"2767874\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/now-fertility.com\/fr\/services\/selection-du-sexe\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus sur la s\u00e9lection du sexe<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6961\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6961\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Le PGT est-il fait pour moi ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6961\" class=\"elementor-element elementor-element-3fb6abc e-con-full e-flex e-con e-child\" data-id=\"3fb6abc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b77f51b elementor-widget elementor-widget-text-editor\" data-id=\"b77f51b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En g\u00e9n\u00e9ral, le PGT n\u2019am\u00e9liore pas le taux de grossesse chez les patientes en FIV, en particulier celles de moins de 35 ans. Cependant, des preuves r\u00e9centes sugg\u00e8rent qu\u2019il peut r\u00e9duire le risque de fausse couche et augmenter le taux de naissances vivantes chez les femmes de plus de 37 ans. Il peut \u00e9galement r\u00e9duire votre risque d\u2019avoir un b\u00e9b\u00e9 atteint d\u2019anomalies chromosomiques. Le PGT est g\u00e9n\u00e9ralement propos\u00e9 pour les raisons suivantes :   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b77a427 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b77a427\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Femmes de plus de 35 ans<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c9checs r\u00e9p\u00e9t\u00e9s de FIV (&gt; 3 cycles infructueux malgr\u00e9 le transfert d\u2019embryons de bonne qualit\u00e9)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ant\u00e9c\u00e9dents de fausses couches r\u00e9currentes (&gt; 3 pertes de grossesse cons\u00e9cutives)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Infertilit\u00e9 masculine s\u00e9v\u00e8re<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Couples ayant des ant\u00e9c\u00e9dents familiaux connus de conditions g\u00e9n\u00e9tiques, ou \u00e9tant porteurs ou affect\u00e9s par une mutation g\u00e9n\u00e9tique et\/ou un marqueur connu<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6962\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6962\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment fonctionne le PGT avec NOW-fertility ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6962\" class=\"elementor-element elementor-element-b629817 e-con-full e-flex e-con e-child\" data-id=\"b629817\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a68c7d9 elementor-widget elementor-widget-text-editor\" data-id=\"a68c7d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le PGT implique une biopsie et le pr\u00e9l\u00e8vement d\u2019un petit nombre de cellules d\u2019un embryon afin de le d\u00e9pister pour les anomalies et conditions chromosomiques.<\/p><p>La biopsie est souvent r\u00e9alis\u00e9e sur des embryons de jour 5 ou 6. \u00c0 ce stade de d\u00e9veloppement, l\u2019embryon est appel\u00e9 blastocyste et se compose d\u2019une masse cellulaire interne et d\u2019une couche externe de cellules, connue sous le nom de trophectoderme. La masse cellulaire interne se d\u00e9veloppera finalement en f\u0153tus, tandis que les cellules du trophectoderme deviendront le placenta. Les biopsies sont pr\u00e9lev\u00e9es sur le trophectoderme, et les cellules qui formeront le b\u00e9b\u00e9 sont laiss\u00e9es intactes et ne sont pas biopsi\u00e9es pour les tests.   <\/p><p>Apr\u00e8s la biopsie, les embryons sont congel\u00e9s en attendant les r\u00e9sultats du PGT. La patiente sera programm\u00e9e pour un cycle de transfert d\u2019embryons congel\u00e9s \u00e0 une date ult\u00e9rieure. Le PGT est une proc\u00e9dure s\u00fbre et est propos\u00e9 par la plupart des <a href=\"https:\/\/now-fertility.com\/fr\/centres\/\">cliniques de FIV<\/a> de pointe.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6963\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6963\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> O\u00f9 puis-je faire un PGT avec NOW-fertility ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6963\" class=\"elementor-element elementor-element-0caa35a e-con-full e-flex e-con e-child\" data-id=\"0caa35a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9b41ec elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c9b41ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c9gypte<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gr\u00e8ce<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Italie<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pologne<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Arabie saoudite<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Espagne<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Turquie<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c9mirats arabes unis<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Royaume-Uni<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6964\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6964\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> PGT-A pour indications non m\u00e9dicales : S\u00e9lection du sexe <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6964\" class=\"elementor-element elementor-element-62adeb3 e-con-full e-flex e-con e-child\" data-id=\"62adeb3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12c3191 elementor-widget elementor-widget-text-editor\" data-id=\"12c3191\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le PGT-A a permis aux patients de conna\u00eetre le sexe de leurs embryons. La s\u00e9lection du sexe pour des raisons m\u00e9dicales est utilis\u00e9e pour pr\u00e9venir la naissance d\u2019enfants atteints de certaines maladies g\u00e9n\u00e9tiques li\u00e9es au sexe. Cependant, l\u2019int\u00e9r\u00eat des patients pour la s\u00e9lection du sexe de leur enfant (s\u00e9lection du sexe non m\u00e9dicale) \u00e0 l\u2019aide du PGT-A semble augmenter. Les indications pour la s\u00e9lection du sexe non m\u00e9dicale incluent \u00ab l\u2019\u00e9quilibre familial \u00bb (avoir un enfant du sexe oppos\u00e9 aux enfants pr\u00e9c\u00e9dents) et la pr\u00e9f\u00e9rence personnelle (opter pour un enfant masculin ou f\u00e9minin pour l\u2019exp\u00e9rience unique d\u2019\u00e9lever un enfant d\u2019un sexe ou de l\u2019autre). Le processus de s\u00e9lection du sexe est pr\u00e9cis \u00e0 &gt;99 %.    <\/p><p>L\u2019utilisation de la FIV et du PGT-A pour la s\u00e9lection non m\u00e9dicale du sexe a fait l\u2019objet d\u2019un d\u00e9bat continu entre le public et les professionnels. Bien que la s\u00e9lection non m\u00e9dicale du sexe soit interdite dans de nombreux pays, elle est autoris\u00e9e et acceptable dans certains pays.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Types de PGT\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Il existe diff\\u00e9rents types de services de tests g\\u00e9n\\u00e9tiques utilis\\u00e9s dans divers sc\\u00e9narios. Lorsque vous d\\u00e9cidez de subir ou non un PGT dans le cadre de votre cycle de FIV, votre sp\\u00e9cialiste de la fertilit\\u00e9, parfois en collaboration avec un conseiller g\\u00e9n\\u00e9tique, travaillera avec vous pour s\\u00e9lectionner le meilleur test adapt\\u00e9 \\u00e0 vos ant\\u00e9c\\u00e9dents, votre cas clinique et vos pr\\u00e9f\\u00e9rences. \\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t            \\n            \\n\\t\\t\\t\\t\\tTest g\\u00e9n\\u00e9tique pr\\u00e9implantatoire pour l\\u2019aneuplo\\u00efdie (PGT-A)Le PGT-A est la forme la plus courante de test d\\u2019embryons. Il v\\u00e9rifie si un embryon poss\\u00e8de le bon nombre de chromosomes. Le nombre correct de chromosomes (46), \\u00e9galement appel\\u00e9 euplo\\u00efde, est n\\u00e9cessaire pour que l\\u2019embryon devienne un enfant normal. Lorsque les cellules d\\u2019un embryon ont un nombre incorrect de chromosomes, soit trop peu, soit trop, on parle alors d\\u2019aneuplo\\u00efdie. Il peut \\u00e9galement vous indiquer si un embryon est masculin ou f\\u00e9minin (XY ou XX).    \\nLa pr\\u00e9valence des embryons aneuplo\\u00efdes augmente avec l\\u2019\\u00e2ge des femmes. Les embryons pr\\u00e9sentant une aneuplo\\u00efdie sont plus susceptibles d\\u2019entra\\u00eener une fausse couche pr\\u00e9coce ou un \\u00e9chec de cycle de FIV, quelle que soit leur apparence morphologique. Moins fr\\u00e9quemment, les embryons aneuplo\\u00efdes peuvent entra\\u00eener la naissance d\\u2019un enfant atteint d\\u2019une anomalie chromosomique, comme le syndrome de Down (trisomie 21).  \\nEn plus du syndrome de Down, le PGT-A peut d\\u00e9tecter d\\u2019autres anomalies g\\u00e9n\\u00e9tiques chromosomiques compl\\u00e8tes telles que le syndrome de Turner (XO) et le syndrome de Klinefelter (XXY). Le PGT-A aurait un taux de pr\\u00e9cision \\u00e9lev\\u00e9 d\\u2019environ 98 %. \\nUn embryon normal PGT-A a une chance estim\\u00e9e de 60 % de donner lieu \\u00e0 une naissance vivante apr\\u00e8s un cycle de transfert. \\n\\n\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\tTest g\\u00e9n\\u00e9tique pr\\u00e9implantatoire pour les maladies monog\\u00e9niques (PGT-M)Le PGT-M est utilis\\u00e9 pour confirmer si une condition h\\u00e9r\\u00e9ditaire sp\\u00e9cifique est pr\\u00e9sente dans les embryons d\\u2019une patiente. Il permet aux couples ayant une condition g\\u00e9n\\u00e9tique h\\u00e9r\\u00e9ditaire dans leur famille d\\u2019\\u00e9viter de la transmettre \\u00e0 leurs enfants. Le PGT-M est g\\u00e9n\\u00e9ralement recommand\\u00e9 dans les cas o\\u00f9 l\\u2019un des partenaires ou les deux ont des ant\\u00e9c\\u00e9dents connus de conditions g\\u00e9n\\u00e9tiques dans leur famille. Voici quelques exemples de maladies monog\\u00e9niques courantes pouvant \\u00eatre diagnostiqu\\u00e9es avec le PGT-M : la thalass\\u00e9mie, l\\u2019h\\u00e9mophilie A et B, le syndrome de l\\u2019X fragile, la dr\\u00e9panocytose, la mucoviscidose, la dystrophie musculaire de Duchenne, la maladie de Huntington et le syndrome de Marfan.    \\n\\n\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\tTest g\\u00e9n\\u00e9tique pr\\u00e9implantatoire pour les r\\u00e9arrangements chromosomiques structurels (PGT-SR)Le PGT-SR identifie les embryons avec la bonne quantit\\u00e9 de mat\\u00e9riel g\\u00e9n\\u00e9tique (\\u00e9quilibr\\u00e9s\\\/normaux) et les embryons qui ont du mat\\u00e9riel g\\u00e9n\\u00e9tique suppl\\u00e9mentaire ou manquant \\u00e0 la suite d\\u2019une translocation ou d\\u2019un r\\u00e9arrangement (d\\u00e9s\\u00e9quilibr\\u00e9s).\\nCe test est le moins courant et la plupart des patients n\\u2019auront pas besoin de ce type de test. \\n\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\tEn savoir plus sur la s\\u00e9lection du sexe\"}},{\"@type\":\"Question\",\"name\":\"Le PGT est-il fait pour moi ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"En g\\u00e9n\\u00e9ral, le PGT n\\u2019am\\u00e9liore pas le taux de grossesse chez les patientes en FIV, en particulier celles de moins de 35 ans. Cependant, des preuves r\\u00e9centes sugg\\u00e8rent qu\\u2019il peut r\\u00e9duire le risque de fausse couche et augmenter le taux de naissances vivantes chez les femmes de plus de 37 ans. Il peut \\u00e9galement r\\u00e9duire votre risque d\\u2019avoir un b\\u00e9b\\u00e9 atteint d\\u2019anomalies chromosomiques. Le PGT est g\\u00e9n\\u00e9ralement propos\\u00e9 pour les raisons suivantes :   \\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tFemmes de plus de 35 ans\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\u00c9checs r\\u00e9p\\u00e9t\\u00e9s de FIV (&gt; 3 cycles infructueux malgr\\u00e9 le transfert d\\u2019embryons de bonne qualit\\u00e9)\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tAnt\\u00e9c\\u00e9dents de fausses couches r\\u00e9currentes (&gt; 3 pertes de grossesse cons\\u00e9cutives)\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tInfertilit\\u00e9 masculine s\\u00e9v\\u00e8re\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tCouples ayant des ant\\u00e9c\\u00e9dents familiaux connus de conditions g\\u00e9n\\u00e9tiques, ou \\u00e9tant porteurs ou affect\\u00e9s par une mutation g\\u00e9n\\u00e9tique et\\\/ou un marqueur connu\"}},{\"@type\":\"Question\",\"name\":\"Comment fonctionne le PGT avec NOW-fertility ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Le PGT implique une biopsie et le pr\\u00e9l\\u00e8vement d\\u2019un petit nombre de cellules d\\u2019un embryon afin de le d\\u00e9pister pour les anomalies et conditions chromosomiques.La biopsie est souvent r\\u00e9alis\\u00e9e sur des embryons de jour 5 ou 6. \\u00c0 ce stade de d\\u00e9veloppement, l\\u2019embryon est appel\\u00e9 blastocyste et se compose d\\u2019une masse cellulaire interne et d\\u2019une couche externe de cellules, connue sous le nom de trophectoderme. La masse cellulaire interne se d\\u00e9veloppera finalement en f\\u0153tus, tandis que les cellules du trophectoderme deviendront le placenta. Les biopsies sont pr\\u00e9lev\\u00e9es sur le trophectoderme, et les cellules qui formeront le b\\u00e9b\\u00e9 sont laiss\\u00e9es intactes et ne sont pas biopsi\\u00e9es pour les tests.   Apr\\u00e8s la biopsie, les embryons sont congel\\u00e9s en attendant les r\\u00e9sultats du PGT. La patiente sera programm\\u00e9e pour un cycle de transfert d\\u2019embryons congel\\u00e9s \\u00e0 une date ult\\u00e9rieure. Le PGT est une proc\\u00e9dure s\\u00fbre et est propos\\u00e9 par la plupart des cliniques de FIV de pointe.\"}},{\"@type\":\"Question\",\"name\":\"O\\u00f9 puis-je faire un PGT avec NOW-fertility ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"\\u00c9gypte\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tGr\\u00e8ce\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tItalie\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tPologne\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tArabie saoudite\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tEspagne\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tTurquie\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\u00c9mirats arabes unis\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\tRoyaume-Uni\"}},{\"@type\":\"Question\",\"name\":\"PGT-A pour indications non m\\u00e9dicales : S\\u00e9lection du sexe\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Le PGT-A a permis aux patients de conna\\u00eetre le sexe de leurs embryons. La s\\u00e9lection du sexe pour des raisons m\\u00e9dicales est utilis\\u00e9e pour pr\\u00e9venir la naissance d\\u2019enfants atteints de certaines maladies g\\u00e9n\\u00e9tiques li\\u00e9es au sexe. Cependant, l\\u2019int\\u00e9r\\u00eat des patients pour la s\\u00e9lection du sexe de leur enfant (s\\u00e9lection du sexe non m\\u00e9dicale) \\u00e0 l\\u2019aide du PGT-A semble augmenter. Les indications pour la s\\u00e9lection du sexe non m\\u00e9dicale incluent \\u00ab l\\u2019\\u00e9quilibre familial \\u00bb (avoir un enfant du sexe oppos\\u00e9 aux enfants pr\\u00e9c\\u00e9dents) et la pr\\u00e9f\\u00e9rence personnelle (opter pour un enfant masculin ou f\\u00e9minin pour l\\u2019exp\\u00e9rience unique d\\u2019\\u00e9lever un enfant d\\u2019un sexe ou de l\\u2019autre). Le processus de s\\u00e9lection du sexe est pr\\u00e9cis \\u00e0 &gt;99 %.    L\\u2019utilisation de la FIV et du PGT-A pour la s\\u00e9lection non m\\u00e9dicale du sexe a fait l\\u2019objet d\\u2019un d\\u00e9bat continu entre le public et les professionnels. Bien que la s\\u00e9lection non m\\u00e9dicale du sexe soit interdite dans de nombreux pays, elle est autoris\\u00e9e et acceptable dans certains pays.\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c30bc2 e-flex e-con-boxed e-con e-parent\" data-id=\"4c30bc2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d5cb16e e-con-full e-flex e-con e-child\" data-id=\"d5cb16e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e4d7a5c e-con-full e-flex e-con e-child\" data-id=\"e4d7a5c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5abb0da e-con-full e-flex e-con e-child\" data-id=\"5abb0da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d1ec34 elementor-widget elementor-widget-heading\" data-id=\"0d1ec34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Des informations pr\u00e9cieuses sur notre blog<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21db2ce elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"21db2ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/now-fertility.com\/fr\/comment-le-conseil-genetique-peut-aider-les-patients-a-prendre-des-decisions\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-comment-dots\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Comment le conseil g\u00e9n\u00e9tique peut aider les patients \u00e0 prendre des d\u00e9cisions<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fe6cee elementor-widget elementor-widget-image\" data-id=\"9fe6cee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/now-fertility.com\/wp-content\/uploads\/2025\/06\/Fertility-Blogs-feature.webp\" class=\"attachment-large size-large wp-image-32024\" alt=\"Blogs sur la fertilit\u00e9\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a975b4 e-con-full e-flex e-con e-child\" data-id=\"1a975b4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-056188e elementor-widget elementor-widget-heading\" data-id=\"056188e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">T\u00e9moignages de patientes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4c349f elementor-widget elementor-widget-text-editor\" data-id=\"e4c349f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Parcourez une s\u00e9lection de nos r\u00e9centes histoires de patients<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-842449f e-con-full e-flex e-con e-parent\" data-id=\"842449f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99cb73b elementor-widget elementor-widget-template\" data-id=\"99cb73b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"38215\" class=\"elementor elementor-38215 elementor-38138 elementor-38138\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d08c975 e-flex e-con-boxed e-con e-parent\" data-id=\"d08c975\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1a15df8 e-con-full e-flex e-con e-child\" data-id=\"1a15df8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7d55d12 e-con-full e-flex e-con e-child\" data-id=\"7d55d12\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-a39ce57 e-con-full e-flex e-con e-child\" data-id=\"a39ce57\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c2914c elementor-widget elementor-widget-heading\" data-id=\"7c2914c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pourquoi choisir NOW-fertility ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-768f8ed elementor-widget elementor-widget-text-editor\" data-id=\"768f8ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre engagement est de rendre les soins de fertilit\u00e9 accessibles, fructueux et sans stress pour les patients <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0009ab elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b0009ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Soins personnalis\u00e9s et de soutien<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Choix des emplacements pratiques<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tarification transparente et garantie<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96cda84 e-con-full e-flex e-con e-child\" data-id=\"96cda84\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-576f62e elementor-widget elementor-widget-heading\" data-id=\"576f62e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Commencez votre parcours avec confiance<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3945e7 elementor-widget elementor-widget-text-editor\" data-id=\"f3945e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Si vous \u00eates pr\u00eat \u00e0 commencer votre d\u00e9marche, prenez rendez-vous avec l\u2019un de nos consultants sp\u00e9cialis\u00e9s en fertilit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b24459b elementor-fixed e-transform elementor-widget elementor-widget-button\" data-id=\"b24459b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;fixed&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-90,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/now-fertility.com\/fr\/contactez-nous\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa9d167 elementor-align-left elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"fa9d167\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/now-fertility.com\/fr\/contactez-nous\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9servez votre consultation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FIV pour PGT S\u00e9lectionner des embryons sains pour une grossesse r\u00e9ussie PGT avec NOW-fertility L\u2019objectif des soins de fertilit\u00e9 est de vous aider \u00e0 avoir une grossesse et un b\u00e9b\u00e9 en bonne sant\u00e9. Le test g\u00e9n\u00e9tique pr\u00e9implantatoire (PGT) est une proc\u00e9dure de d\u00e9pistage effectu\u00e9e sur des embryons cr\u00e9\u00e9s par FIV pour v\u00e9rifier leur sant\u00e9 g\u00e9n\u00e9tique [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32166,"parent":7154,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"disabled","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"enabled","header-above-stick-meta":"on","header-main-stick-meta":"on","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-13559","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FIV pour PGT - NOW-fertility<\/title>\n<meta name=\"description\" content=\"Le test g\u00e9n\u00e9tique pr\u00e9implantatoire (PGT) est un d\u00e9pistage des embryons cr\u00e9\u00e9s par FIV pour analyser g\u00e9n\u00e9tiquement les embryons avant le transfert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FIV pour PGT - NOW-fertility\" \/>\n<meta property=\"og:description\" content=\"Le test g\u00e9n\u00e9tique pr\u00e9implantatoire (PGT) est un d\u00e9pistage des embryons cr\u00e9\u00e9s par FIV pour analyser g\u00e9n\u00e9tiquement les embryons avant le transfert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/\" \/>\n<meta property=\"og:site_name\" content=\"NOW-fertility\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nowfertilitycare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T16:23:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-fertility.com\/wp-content\/uploads\/2025\/06\/IVF-for-PGT-feature.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@nowfertility\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/services\\\/tests-genetiques-preimplantatoires-tcp\\\/\",\"url\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/services\\\/tests-genetiques-preimplantatoires-tcp\\\/\",\"name\":\"FIV pour PGT - NOW-fertility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/services\\\/tests-genetiques-preimplantatoires-tcp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/services\\\/tests-genetiques-preimplantatoires-tcp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-fertility.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/IVF-for-PGT-feature.webp\",\"datePublished\":\"2023-01-13T14:02:00+00:00\",\"dateModified\":\"2026-04-01T16:23:35+00:00\",\"description\":\"Le test g\u00e9n\u00e9tique pr\u00e9implantatoire (PGT) est un d\u00e9pistage des embryons cr\u00e9\u00e9s par FIV pour analyser g\u00e9n\u00e9tiquement les embryons avant le transfert.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/services\\\/tests-genetiques-preimplantatoires-tcp\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-fertility.com\\\/fr\\\/services\\\/tests-genetiques-preimplantatoires-tcp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/services\\\/tests-genetiques-preimplantatoires-tcp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-fertility.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/IVF-for-PGT-feature.webp\",\"contentUrl\":\"https:\\\/\\\/now-fertility.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/IVF-for-PGT-feature.webp\",\"width\":900,\"height\":600,\"caption\":\"FIV pour PGT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/services\\\/tests-genetiques-preimplantatoires-tcp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/domicile\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/services\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FIV pour PGT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/\",\"name\":\"NOW-fertility\",\"description\":\"Global fertility service without barriers\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/#organization\",\"name\":\"NOW-fertility\",\"url\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/now-fertility.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/NOW-fertility.png\",\"contentUrl\":\"https:\\\/\\\/now-fertility.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/NOW-fertility.png\",\"width\":720,\"height\":720,\"caption\":\"NOW-fertility\"},\"image\":{\"@id\":\"https:\\\/\\\/now-fertility.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nowfertilitycare\",\"https:\\\/\\\/x.com\\\/nowfertility\",\"https:\\\/\\\/www.instagram.com\\\/nowfertilitycare\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/nowfertilitycare\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FIV pour PGT - NOW-fertility","description":"Le test g\u00e9n\u00e9tique pr\u00e9implantatoire (PGT) est un d\u00e9pistage des embryons cr\u00e9\u00e9s par FIV pour analyser g\u00e9n\u00e9tiquement les embryons avant le transfert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/","og_locale":"fr_FR","og_type":"article","og_title":"FIV pour PGT - NOW-fertility","og_description":"Le test g\u00e9n\u00e9tique pr\u00e9implantatoire (PGT) est un d\u00e9pistage des embryons cr\u00e9\u00e9s par FIV pour analyser g\u00e9n\u00e9tiquement les embryons avant le transfert.","og_url":"https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/","og_site_name":"NOW-fertility","article_publisher":"https:\/\/www.facebook.com\/nowfertilitycare","article_modified_time":"2026-04-01T16:23:35+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/now-fertility.com\/wp-content\/uploads\/2025\/06\/IVF-for-PGT-feature.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@nowfertility","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/","url":"https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/","name":"FIV pour PGT - NOW-fertility","isPartOf":{"@id":"https:\/\/now-fertility.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/#primaryimage"},"image":{"@id":"https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/#primaryimage"},"thumbnailUrl":"https:\/\/now-fertility.com\/wp-content\/uploads\/2025\/06\/IVF-for-PGT-feature.webp","datePublished":"2023-01-13T14:02:00+00:00","dateModified":"2026-04-01T16:23:35+00:00","description":"Le test g\u00e9n\u00e9tique pr\u00e9implantatoire (PGT) est un d\u00e9pistage des embryons cr\u00e9\u00e9s par FIV pour analyser g\u00e9n\u00e9tiquement les embryons avant le transfert.","breadcrumb":{"@id":"https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/#primaryimage","url":"https:\/\/now-fertility.com\/wp-content\/uploads\/2025\/06\/IVF-for-PGT-feature.webp","contentUrl":"https:\/\/now-fertility.com\/wp-content\/uploads\/2025\/06\/IVF-for-PGT-feature.webp","width":900,"height":600,"caption":"FIV pour PGT"},{"@type":"BreadcrumbList","@id":"https:\/\/now-fertility.com\/fr\/services\/tests-genetiques-preimplantatoires-tcp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/now-fertility.com\/fr\/domicile\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/now-fertility.com\/fr\/services\/"},{"@type":"ListItem","position":3,"name":"FIV pour PGT"}]},{"@type":"WebSite","@id":"https:\/\/now-fertility.com\/fr\/#website","url":"https:\/\/now-fertility.com\/fr\/","name":"NOW-fertility","description":"Global fertility service without barriers","publisher":{"@id":"https:\/\/now-fertility.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-fertility.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/now-fertility.com\/fr\/#organization","name":"NOW-fertility","url":"https:\/\/now-fertility.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/now-fertility.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/now-fertility.com\/wp-content\/uploads\/2023\/11\/NOW-fertility.png","contentUrl":"https:\/\/now-fertility.com\/wp-content\/uploads\/2023\/11\/NOW-fertility.png","width":720,"height":720,"caption":"NOW-fertility"},"image":{"@id":"https:\/\/now-fertility.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nowfertilitycare","https:\/\/x.com\/nowfertility","https:\/\/www.instagram.com\/nowfertilitycare\/","https:\/\/www.linkedin.com\/company\/nowfertilitycare\/"]}]}},"_links":{"self":[{"href":"https:\/\/now-fertility.com\/fr\/wp-json\/wp\/v2\/pages\/13559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-fertility.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/now-fertility.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/now-fertility.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/now-fertility.com\/fr\/wp-json\/wp\/v2\/comments?post=13559"}],"version-history":[{"count":22,"href":"https:\/\/now-fertility.com\/fr\/wp-json\/wp\/v2\/pages\/13559\/revisions"}],"predecessor-version":[{"id":38433,"href":"https:\/\/now-fertility.com\/fr\/wp-json\/wp\/v2\/pages\/13559\/revisions\/38433"}],"up":[{"embeddable":true,"href":"https:\/\/now-fertility.com\/fr\/wp-json\/wp\/v2\/pages\/7154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-fertility.com\/fr\/wp-json\/wp\/v2\/media\/32166"}],"wp:attachment":[{"href":"https:\/\/now-fertility.com\/fr\/wp-json\/wp\/v2\/media?parent=13559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}